{"id":52230,"date":"2019-04-08T10:41:54","date_gmt":"2019-04-08T13:41:54","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52230"},"modified":"2019-04-08T10:41:54","modified_gmt":"2019-04-08T13:41:54","slug":"medicos-devem-ter-a-autonomia-profissional-garantida-defendem-palestrantes-no-i-encm-2019","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/medicos-devem-ter-a-autonomia-profissional-garantida-defendem-palestrantes-no-i-encm-2019\/","title":{"rendered":"M\u00e9dicos devem ter a autonomia profissional garantida, defendem palestrantes no I ENCM 2019"},"content":{"rendered":"<p style=\"text-align: justify;\">\u201cO m\u00e9dico exercer\u00e1 sua profiss\u00e3o com autonomia, n\u00e3o sendo obrigado a prestar servi\u00e7os que contrariem os ditames de sua consci\u00eancia\u201d. Partindo dessa premissa, assegurada no C\u00f3digo de \u00c9tica M\u00e9dica, os palestrantes conduziram os debates da tarde do segundo dia do I Encontro dos Conselhos de Medicina 2019. O tema foi abordado pelas perspectivas dos Sistema \u00danico de Sa\u00fade (SUS) e tamb\u00e9m da Sa\u00fade Suplementar.<\/p>\n<p style=\"text-align: justify;\">Na vis\u00e3o do coordenador da Comiss\u00e3o Nacional Pr\u00f3-SUS, Donizetti Giamberardino, a autonomia \u00e9 a capacidade de pensar, decidir e agir, de modo livre e independente. Apesar disso, ele pontuou uma s\u00e9rie de condi\u00e7\u00f5es que imp\u00f5em limites ao exerc\u00edcio da medicina na rede p\u00fablica. \u201cMuitas vezes a imprensa nos coloca como vil\u00f5es, como se as condi\u00e7\u00f5es da assist\u00eancia fosse m\u00e9dico dependente. Como o m\u00e9dico pode exercer plenamente suas atividades sob m\u00e1 gest\u00e3o dos recursos, corrup\u00e7\u00e3o e em contexto de total adversidade?\u201d, ponderou.<\/p>\n<p style=\"text-align: justify;\">Ele citou, por exemplo, dois recentes levantamentos do CFM que revelam o subfinanciamento e a falta de infraestrutura no SUS. Um deles mostrou que os governos (em n\u00edveis federal, estaduais e municipais) aplicaram, diariamente, cerca de R$ 3,48 per capita para cobrir as despesas p\u00fablicas com sa\u00fade dos brasileiros em 2017. Outro aponta para uma queda de mais de 34 mil leitos de interna\u00e7\u00e3o desde 2010. \u201cO exerc\u00edcio da medicina em meio ao caos oferece riscos \u00e0 seguran\u00e7a do paciente e coloca o m\u00e9dico em situa\u00e7\u00e3o de vulnerabilidade\u201d, alertou.<\/p>\n<p style=\"text-align: justify;\"><strong>Sa\u00fade suplementar \u2013<\/strong> J\u00e1 o coordenador da Comiss\u00e3o Nacional de Sa\u00fade Suplementar do CFM (Comsu), Salom\u00e3o Rodrigues, destacou que a autonomia do m\u00e9dico vem passando por intensas modifica\u00e7\u00f5es. Entre os principais motivos, segundo ele, est\u00e3o o progressivo aumento do conhecimento m\u00e9dico ao longo dos anos, o acelerado avan\u00e7o tecnol\u00f3gico, a instala\u00e7\u00e3o da crise financeira e limita\u00e7\u00f5es econ\u00f4micas do Brasil, entre outros.<\/p>\n<p style=\"text-align: justify;\">Como poss\u00edveis solu\u00e7\u00f5es para superar os desafios existentes no \u00e2mbito da sa\u00fade suplementar, Rodrigues prop\u00f5e que sejam organizadas comiss\u00f5es de honor\u00e1rios m\u00e9dicos em todos os estados, que haja uma participa\u00e7\u00e3o pol\u00edtica mais efetiva da classe, que as associa\u00e7\u00f5es de especialidades sejam atuantes e habituadas a negociar com as operadoras de planos de sa\u00fade e que as den\u00fancias de poss\u00edveis infra\u00e7\u00f5es \u00e9ticas sejam levadas aos Conselhos de Medicina.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o do Cremepe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO m\u00e9dico exercer\u00e1 sua profiss\u00e3o com autonomia, n\u00e3o sendo obrigado a prestar servi\u00e7os que contrariem os ditames de sua consci\u00eancia\u201d. Partindo dessa premissa, assegurada no C\u00f3digo de \u00c9tica M\u00e9dica, os palestrantes conduziram os debates da tarde do segundo dia do I Encontro dos Conselhos de Medicina 2019. O tema foi abordado pelas perspectivas dos Sistema [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[2275,389,75],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52230"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52230"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52230\/revisions"}],"predecessor-version":[{"id":52231,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52230\/revisions\/52231"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}