{"id":52306,"date":"2019-04-12T08:40:34","date_gmt":"2019-04-12T11:40:34","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52306"},"modified":"2019-04-16T18:07:50","modified_gmt":"2019-04-16T21:07:50","slug":"fmb-reunida-em-3o-conselho-deliberativo-trata-de-acoes-politicas-de-representatividade","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/fmb-reunida-em-3o-conselho-deliberativo-trata-de-acoes-politicas-de-representatividade\/","title":{"rendered":"FMB reunida em 3\u00ba Conselho Deliberativo trata de a\u00e7\u00f5es pol\u00edticas de representatividade"},"content":{"rendered":"<p style=\"text-align: justify;\">Reunida em sua terceira edi\u00e7\u00e3o de Conselho Deliberativo, na sede do Sindicato dos M\u00e9dicos do Rio de Janeiro, no Rio de Janeiro, dirigentes da Federa\u00e7\u00e3o M\u00e9dica Brasileira (FMB) trataram no primeiro dia de atividade sobre a representa\u00e7\u00e3o pol\u00edtica da entidade, aprovaram o balan\u00e7o financeiro da Entidade e o financiamento das atividades tendo em vista o fim da contribui\u00e7\u00e3o sindical.<\/p>\n<p style=\"text-align: justify;\">O evento termina na sexta-feira, dia 12 de abril, com palestra sobre Mercado de Trabalho para o M\u00e9dico p\u00f3s Reforma Trabalhista, com a advogada Zilmara Alencar e a participa\u00e7\u00e3o da secret\u00e1ria de Gest\u00e3o do Trabalho e da Educa\u00e7\u00e3o da Sa\u00fade (SGTES), Mayra Pinheiro, que vai tratar sobre Rumos da Sa\u00fade na Atual Gest\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O presidente da FMB, Casemiro dos Reis J\u00fanior lembra que a representatividade pol\u00edtica da Entidade \u00e9 muito importante. \u201cTemos que estar presentes dentro do debate pol\u00edtico e isso significa investimento em representatividade. Temos compromisso em Bras\u00edlia em v\u00e1rias inst\u00e2ncias e os debates est\u00e3o sendo realizados. Se n\u00e3o estivermos l\u00e1, vamos encolher\u201d, declarou.<\/p>\n<p style=\"text-align: justify;\">O CD tamb\u00e9m confirmou para os dias 24 e 25 de outubro um Congresso Extraordin\u00e1rio, que ser\u00e1 realizado na cidade de Campinas (SP). \u201cA nova conjuntura exige altera\u00e7\u00f5es no estatuto da FMB e vamos debater pontos que beneficiar\u00e3o a nossa Entidade e como consequ\u00eancia, as nossas atividades\u201d, acrescenta Casemiro.<\/p>\n<p style=\"text-align: justify;\">Sobre os trabalhos pol\u00edticos da Entidade, a secret\u00e1ria de Finan\u00e7as, Malu David, relatou o empenho dos dirigentes da FMB na participa\u00e7\u00e3o na Comiss\u00e3o de Assuntos Pol\u00edticos (CAP\/CFM) e tamb\u00e9m no Instituto Brasil da Medicina (IBDM). \u201cS\u00e3o trabalhos que nos exigem dedica\u00e7\u00e3o e comprometimento. Temos que estar l\u00e1 sob pena de nunca termos nossas pautas sequer ouvidas. \u00c9 um trabalho de constru\u00e7\u00e3o que n\u00e3o ser\u00e1 realizado da noite para o dia. Temos que estar presentes e participantes\u201d, alertou.<\/p>\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o da Federa\u00e7\u00e3o M\u00e9dica Brasileira (FMB)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reunida em sua terceira edi\u00e7\u00e3o de Conselho Deliberativo, na sede do Sindicato dos M\u00e9dicos do Rio de Janeiro, no Rio de Janeiro, dirigentes da Federa\u00e7\u00e3o M\u00e9dica Brasileira (FMB) trataram no primeiro dia de atividade sobre a representa\u00e7\u00e3o pol\u00edtica da entidade, aprovaram o balan\u00e7o financeiro da Entidade e o financiamento das atividades tendo em vista o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[1],"tags":[3534,215,4],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52306"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52306"}],"version-history":[{"count":4,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52306\/revisions"}],"predecessor-version":[{"id":52403,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52306\/revisions\/52403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media\/52335"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}