{"id":52341,"date":"2019-04-15T10:00:42","date_gmt":"2019-04-15T13:00:42","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52341"},"modified":"2019-04-15T10:00:42","modified_gmt":"2019-04-15T13:00:42","slug":"reforma-cria-trava-para-liberacao-de-remedio-no-sus","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/reforma-cria-trava-para-liberacao-de-remedio-no-sus\/","title":{"rendered":"Reforma cria trava para libera\u00e7\u00e3o de rem\u00e9dio no SUS"},"content":{"rendered":"<p style=\"text-align: justify;\">O texto original da Reforma poder\u00e1 reduzir distribui\u00e7\u00e3o de rem\u00e9dios a pacientes da rede p\u00fablica de sa\u00fade obtidos com decis\u00e3o judicial<\/p>\n<p style=\"text-align: justify;\">A reforma da Previd\u00eancia, se aprovada com o texto original apresentado pelo presidente Jair Bolsonaro (PSL), poder\u00e1 reduzir a distribui\u00e7\u00e3o de rem\u00e9dios a pacientes da rede p\u00fablica de sa\u00fade obtidos com decis\u00e3o judicial. A PEC (Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o) com novas regras para aposentadorias e pens\u00f5es dever\u00e1 limitar a judicializa\u00e7\u00e3o da sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">A press\u00e3o das senten\u00e7as sobre os Or\u00e7amentos de munic\u00edpios, estados e Uni\u00e3o aumenta ano ap\u00f3s ano. Esse custo extra desafia o equil\u00edbrio das contas p\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">\nApenas em 2018, segundo dados do Minist\u00e9rio da Sa\u00fade, foi gasto R$ 1,4 bilh\u00e3o pela Uni\u00e3o com medicamentos e tratamentos por determina\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\">A proposta de Bolsonaro e do ministro da Economia, Paulo Guedes, altera o par\u00e1grafo 5\u00b0 do artigo 195 da Constitui\u00e7\u00e3o. O trecho trata do or\u00e7amento da seguridade social, que abrange sa\u00fade, Previd\u00eancia e assist\u00eancia social. &#8220;Nenhum benef\u00edcio ou servi\u00e7o da seguridade social poder\u00e1 ser criado, majorado ou estendido por ato administrativo, lei ou decis\u00e3o judicial, sem a correspondente fonte de custeio total&#8221;, diz a PEC.<\/p>\n<p style=\"text-align: justify;\">A nova reda\u00e7\u00e3o inclui na Constitui\u00e7\u00e3o os termos &#8220;por ato administrativo, lei ou decis\u00e3o judicial&#8221;. Esse arranjo, segundo especialistas, poder\u00e1 dificultar o acesso a rem\u00e9dios e tratamentos. &#8220;Embora tenha o apelido de &#8216;PEC da Previd\u00eancia&#8217;, o texto abarca a judicializa\u00e7\u00e3o da sa\u00fade&#8221;, afirma Roberto Dias, professor de direito constitucional da FGV-SP (Funda\u00e7\u00e3o Getulio Vargas de S\u00e3o Paulo).<\/p>\n<p style=\"text-align: justify;\">Para ele, esse trecho \u00e9 inconstitucional. Por\u00e9m, o relator da reforma na CCJ (Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a) da C\u00e2mara, Marcelo Freitas (PSL-MG), j\u00e1 deu aval ao texto. &#8220;Ao se dizer que uma decis\u00e3o judicial n\u00e3o pode ser proferida sem fonte de custeio, est\u00e1 se violando a possibilidade de acesso \u00e0 Justi\u00e7a. Essa \u00e9 uma cl\u00e1usula p\u00e9trea [que n\u00e3o poderia ser alterada]&#8221;, afirma Dias.<\/p>\n<p style=\"text-align: justify;\">Segundo o professor, a PEC tenta conter o aumento de despesas. &#8220;A inten\u00e7\u00e3o \u00e9 louv\u00e1vel, mas n\u00e3o d\u00e1 para desconsiderar as reiteradas viola\u00e7\u00f5es de direitos praticadas pelo pr\u00f3prio poder p\u00fablico&#8221;, diz. O professor de direito previdenci\u00e1rio da USP (Universidade de S\u00e3o Paulo) Marcus Orione tamb\u00e9m v\u00ea entraves no acesso \u00e0 Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\">&#8220;A PEC traz problemas s\u00e9rios porque imp\u00f5e restri\u00e7\u00f5es aos direitos fundamentais, seja em a\u00e7\u00e3o individual, seja em a\u00e7\u00e3o coletiva&#8221;, afirma. Para o presidente da Ajufe (Associa\u00e7\u00e3o dos Ju\u00edzes Federais), Fernando Mendes, cabe a um magistrado apenas julgar \u2013interpretar as leis e a Constitui\u00e7\u00e3o para chegar a uma decis\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8220;N\u00e3o \u00e9 papel do juiz entrar em quest\u00f5es or\u00e7ament\u00e1rias, alocar recursos, ou de alguma maneira definir de onde v\u00e3o sair os recursos&#8221;, diz Mendes. Hoje j\u00e1 h\u00e1 leis que obrigam ju\u00edzes a atentar \u00e0s consequ\u00eancias de decis\u00f5es. Segundo os especialistas ouvidos pela reportagem, essas normas, no entanto, n\u00e3o se sobrep\u00f5em \u00e0 Constitui\u00e7\u00e3o, que a PEC visa alterar.<\/p>\n<p style=\"text-align: justify;\">&#8220;Uma coisa \u00e9 uma norma ordin\u00e1ria, outra \u00e9 uma norma constitucional&#8221;, diz Mendes.<br \/>\nEm meio a esse impasse, as contas n\u00e3o fecham. Entre 2008 e 2018, a Uni\u00e3o desembolsou R$ 7 bilh\u00f5es para a compra de medicamentos e a oferta de tratamentos -crescimento de 1.711% no per\u00edodo. A regra da PEC se estender\u00e1 a estados e munic\u00edpios. Em 2017, o ent\u00e3o ministro da Sa\u00fade de Michel Temer (MDB), Ricardo Barros, estimou em R$ 7 bilh\u00f5es os gastos dos demais entes da Federa\u00e7\u00e3o com senten\u00e7as judiciais.<\/p>\n<p style=\"text-align: justify;\">O professor de estrat\u00e9gia no setor p\u00fablico do Insper Sandro Cabral reconhece o peso desses processos. &#8220;A preocupa\u00e7\u00e3o do Executivo em controlar as contas p\u00fablicas e garantir o Or\u00e7amento \u00e9 leg\u00edtima.&#8221;<\/p>\n<p style=\"text-align: justify;\">Segundo ele, a judicializa\u00e7\u00e3o \u00e9 um processo &#8220;superconcentrador de renda&#8221;. &#8220;Um mun\u00edcipe pode ficar com boa parte do or\u00e7amento [da sa\u00fade]&#8221;, diz o professor.<br \/>\nCabral, no entanto, afirma que a sa\u00edda para esse dilema exige debate. &#8220;Para alterar qualquer pol\u00edtica p\u00fablica, tem de conversar com as partes envolvidas e buscar solu\u00e7\u00e3o fact\u00edvel para todas elas&#8221;, diz.<\/p>\n<p style=\"text-align: justify;\">Ele ainda levanta d\u00favidas sobre como magistrados poder\u00e3o exercer o controle dos gastos p\u00fablicos. &#8220;O juiz vai ter acesso a quest\u00f5es de or\u00e7amento? Como se dar\u00e1 essa interface?&#8221;, questiona Cabral. Segundo os especialistas em direito, se a regra for aprovada, a execu\u00e7\u00e3o no dia a dia depender\u00e1 da interpreta\u00e7\u00e3o de cada juiz, que poder\u00e1 recorrer a outras normas para justificar a concess\u00e3o de rem\u00e9dio. Ele poder\u00e1 tamb\u00e9m, com base na nova reda\u00e7\u00e3o, neg\u00e1-lo.<\/p>\n<p style=\"text-align: justify;\">Entidades que representam secret\u00e1rios municipais e estaduais de Sa\u00fade de todo o Brasil minimizam os efeitos da PEC. Em nota, o Conasems (conselho de secret\u00e1rios municipais) diz que o texto, &#8220;considerando sua reda\u00e7\u00e3o bastante gen\u00e9rica, n\u00e3o impactar\u00e1 a interpreta\u00e7\u00e3o do Judici\u00e1rio&#8221; e n\u00e3o limitar\u00e1 a judicializa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O Conass (conselho dos gestores estaduais de sa\u00fade) informa que a proposta ainda n\u00e3o foi pauta de assembleia-geral dos 27 secret\u00e1rios. As entidades n\u00e3o disp\u00f5em de dados locais e regionais. No campo previdenci\u00e1rio, a inten\u00e7\u00e3o principal \u00e9 impedir a expans\u00e3o de gastos do INSS (Instituto Nacional do Seguro Social) via ordem judicial.<br \/>\nSegundo o TCU (Tribunal de Contas da Uni\u00e3o), em 2017, foram R$ 92 bilh\u00f5es pagos a segurados por meio de senten\u00e7as. O valor equivale a 15% dos R$ 609 bilh\u00f5es em benef\u00edcios.<\/p>\n<p style=\"text-align: justify;\">A PEC atualmente est\u00e1 em debate na CCJ da C\u00e2mara. Ap\u00f3s a an\u00e1lise no colegiado, o texto segue para uma comiss\u00e3o especial. De l\u00e1, ser\u00e1 encaminhado ao plen\u00e1rio. S\u00e3o necess\u00e1rios 308 votos dos 513 deputados em duas sess\u00f5es. A proposta, ent\u00e3o, ir\u00e1 para o Senado. S\u00e3o necess\u00e1rios 49 votos, tamb\u00e9m em dois turnos.<\/p>\n<p style=\"text-align: justify;\"><strong>Outro lado<\/strong><br \/>\nA Secretaria de Previd\u00eancia e Trabalho nega, em nota, que a altera\u00e7\u00e3o do par\u00e1grafo 5\u00ba do artigo 195 da Constitui\u00e7\u00e3o tenha o objetivo de &#8220;impedir que demandas sejam submetidas ao Poder Judici\u00e1rio e por ele apreciadas&#8221;.<\/p>\n<p style=\"text-align: justify;\">De acordo com o \u00f3rg\u00e3o do Minist\u00e9rio da Economia respons\u00e1vel pela reforma da Previd\u00eancia, o acesso \u00e0 Justi\u00e7a \u00e9 direito fundamental previsto no artigo 5\u00ba da Constitui\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8220;[A PEC] Tem, no entanto, o objetivo de estabelecer que o Poder Judici\u00e1rio n\u00e3o pode, por meio de suas decis\u00f5es, criar novo benef\u00edcio ou ampliar a abrang\u00eancia de um determinado benef\u00edcio sem existir a fonte de custeio&#8221;, diz.<\/p>\n<p style=\"text-align: justify;\">Na exposi\u00e7\u00e3o de motivos da PEC, enviada ao presidente Jair Bolsonaro (PSL) e ao Congresso, o ministro da Economia, Paulo Guedes, afirma que a &#8220;redu\u00e7\u00e3o da judicializa\u00e7\u00e3o&#8221; \u00e9 um dos &#8220;pilares fundamentais&#8221; da reforma. De acordo com a secretaria, ao decidir pela amplia\u00e7\u00e3o de um benef\u00edcio ou servi\u00e7o, o Judici\u00e1rio entra no campo de defini\u00e7\u00e3o de pol\u00edticas p\u00fablicas \u2013uma responsabilidade do Executivo e do Legislativo.<\/p>\n<p style=\"text-align: justify;\">A nova regra, confirma a secretaria, abrange Previd\u00eancia, assist\u00eancia social e sa\u00fade.<br \/>\nEmbora um dos principais objetivos da reforma da Previd\u00eancia seja equilibrar as contas p\u00fablicas, o \u00f3rg\u00e3o informa que &#8220;n\u00e3o houve estudo espec\u00edfico&#8221; para o impacto fiscal. &#8220;A altera\u00e7\u00e3o foi proposta por princ\u00edpio&#8221;, diz a secretaria.<\/p>\n<p style=\"text-align: justify;\"><strong>Doen\u00e7as raras<\/strong><br \/>\nDados do Minist\u00e9rio da Sa\u00fade mostram que 90% do total gasto para atender senten\u00e7as judiciais se refere a rem\u00e9dios para tratamento de doen\u00e7as raras. Houve tamb\u00e9m decis\u00f5es, segundo a pasta, para a distribui\u00e7\u00e3o de \u00e1lcool em gel, \u00f3leo de girassol, protetor solar e xampu anticaspa.<\/p>\n<p style=\"text-align: justify;\">O minist\u00e9rio afirma, em nota, que a judicializa\u00e7\u00e3o &#8220;tem consumido parte importante dos or\u00e7amentos da Uni\u00e3o, de estados e de munic\u00edpios&#8221;. Hoje, a pasta cumpre senten\u00e7as de 14.785 processos. A maior parte \u00e9 de medicamentos (82%), em seguida v\u00eam procedimentos (10%), interna\u00e7\u00f5es (5%) e insumos (3%).<\/p>\n<p style=\"text-align: justify;\">Com dez tipos de rem\u00e9dio, a Uni\u00e3o desembolsou no ano passado R$ 1,2 bilh\u00e3o e atendeu 1.596 pacientes. O minist\u00e9rio atua, desde 2016, em parceria com o CNJ (Conselho Nacional de Justi\u00e7a) para fornecer subs\u00eddios para ju\u00edzes sobre a efetividade cl\u00ednica dos medicamentos.<\/p>\n<p style=\"text-align: justify;\">Ferramenta da pasta, do CNJ e do Hospital S\u00edrio-Liban\u00eas, lan\u00e7ada em 2017, permite ao magistrado consultar os benef\u00edcios comprovados dos rem\u00e9dios pedidos. O e-NatJus, sistema online com informa\u00e7\u00f5es cl\u00ednicas, cont\u00e9m atualmente 42 pareceres t\u00e9cnico-cient\u00edficos. &#8220;A \u00e1rea [t\u00e9cnica da pasta] tem garantido o atendimento \u00e0s decis\u00f5es e a entrega aos pacientes e verificado se o pedido poder\u00e1 ser suprido no pr\u00f3prio SUS [Sistema \u00danico de Sa\u00fade]&#8221;, informa a pasta da Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Folha de Pernambuco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O texto original da Reforma poder\u00e1 reduzir distribui\u00e7\u00e3o de rem\u00e9dios a pacientes da rede p\u00fablica de sa\u00fade obtidos com decis\u00e3o judicial A reforma da Previd\u00eancia, se aprovada com o texto original apresentado pelo presidente Jair Bolsonaro (PSL), poder\u00e1 reduzir a distribui\u00e7\u00e3o de rem\u00e9dios a pacientes da rede p\u00fablica de sa\u00fade obtidos com decis\u00e3o judicial. A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[468,413,34],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52341"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52341"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52341\/revisions"}],"predecessor-version":[{"id":52342,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52341\/revisions\/52342"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}