{"id":52416,"date":"2019-04-17T11:26:11","date_gmt":"2019-04-17T14:26:11","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52416"},"modified":"2019-04-17T11:26:11","modified_gmt":"2019-04-17T14:26:11","slug":"novo-codigo-de-etica-medica-apresentado-a-bolsonaro-entra-em-vigor-no-fim-do-mes","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/novo-codigo-de-etica-medica-apresentado-a-bolsonaro-entra-em-vigor-no-fim-do-mes\/","title":{"rendered":"Novo C\u00f3digo de \u00c9tica M\u00e9dica apresentado a Bolsonaro entra em vigor no fim do m\u00eas"},"content":{"rendered":"<p style=\"text-align: justify;\"><img src=\"http:\/\/portal.cfm.org.br\/images\/stories\/Noticias2019\/audiencia%20com%20o%20presidente%20jair%20bolsonaro%20grande%202.jpg\" alt=\"O presidente Jair Bolsonaro conheceu os destaques da atualiza\u00c3\u00a7\u00c3\u00a3o do C\u00c3\u00b3digo de \u00c3\u0089tica M\u00c3\u00a9dica\" \/><\/p>\n<p style=\"text-align: justify;\">No encontro com o presidente Jair Bolsonario, os representantes do CFM detalharam pontos que se destacam no C\u00f3digo de \u00c9tica M\u00e9dica, que cont\u00e9m normas que devem ser seguidas por organiza\u00e7\u00f5es de presta\u00e7\u00e3o de servi\u00e7os m\u00e9dicos e pelos m\u00e9dicos no exerc\u00edcio de sua profiss\u00e3o. O texto passa a valer a partir de 30 de abril.<\/p>\n<p>\u201cAo atender uma necessidade natural e permanente de aperfei\u00e7oamento, a revis\u00e3o do C\u00f3digo de \u00c9tica M\u00e9dica foi feita sob o prisma de zelo pelos princ\u00edpios deontol\u00f3gicos da medicina, sendo um dos mais importantes o absoluto respeito ao ser humano, com a atua\u00e7\u00e3o em prol da sa\u00fade dos indiv\u00edduos e da coletividade, sem discrimina\u00e7\u00f5es\u201d, disse a conselheira Rosylane Rocha, que participou do grupo que coordenou o processo.<\/p>\n<p>O novo texto atualizou a vers\u00e3o anterior, de 2009, incorporando abordagens pertinentes \u00e0s mudan\u00e7as do mundo contempor\u00e2neo. Temas como inova\u00e7\u00f5es tecnol\u00f3gicas, comunica\u00e7\u00e3o em massa e rela\u00e7\u00f5es em sociedade foram tratados, dentre outros. As mudan\u00e7as resultaram de 1.431 propostas enviadas por associa\u00e7\u00f5es m\u00e9dicas, sociedades de especialidades, entidades de ensino m\u00e9dico, dentre outras organiza\u00e7\u00f5es, sendo que \u201co documento final refor\u00e7a o compromisso \u00e9tico da categoria com o bem-estar e a sa\u00fade dos pacientes, coibindo intera\u00e7\u00f5es com fim de lucro, incompat\u00edveis com os princ\u00edpios da boa medicina\u201d, resumiu ela.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o do CFM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No encontro com o presidente Jair Bolsonario, os representantes do CFM detalharam pontos que se destacam no C\u00f3digo de \u00c9tica M\u00e9dica, que cont\u00e9m normas que devem ser seguidas por organiza\u00e7\u00f5es de presta\u00e7\u00e3o de servi\u00e7os m\u00e9dicos e pelos m\u00e9dicos no exerc\u00edcio de sua profiss\u00e3o. O texto passa a valer a partir de 30 de abril. \u201cAo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[67,92,82],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52416"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52416"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52416\/revisions"}],"predecessor-version":[{"id":52417,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52416\/revisions\/52417"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}