{"id":52418,"date":"2019-04-17T11:38:41","date_gmt":"2019-04-17T14:38:41","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52418"},"modified":"2019-04-17T11:38:41","modified_gmt":"2019-04-17T14:38:41","slug":"ao-apresentar-novo-codigo-de-etica-medica-cfm-faz-pedidos-ao-presidente-jair-bolsonaro-em-nome-dos-medicos","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/ao-apresentar-novo-codigo-de-etica-medica-cfm-faz-pedidos-ao-presidente-jair-bolsonaro-em-nome-dos-medicos\/","title":{"rendered":"Ao apresentar novo C\u00f3digo de \u00c9tica M\u00e9dica, CFM faz pedidos ao presidente Jair Bolsonaro em nome dos m\u00e9dicos"},"content":{"rendered":"<p style=\"text-align: justify;\">Numa reuni\u00e3o de quase duas horas, no Pal\u00e1cio do Planalto, a diretoria do Conselho Federal de Medicina (CFM) apresentou hoje (16) ao presidente da Rep\u00fablica, Jair Bolsonaro, e ao ministro da Sa\u00fade, Henrique Mandetta, o novo C\u00f3digo de \u00c9tica M\u00e9dica (CEM), detalhado na Resolu\u00e7\u00e3o n\u00ba 2.217\/2018 e que entra vigor no pr\u00f3ximo dia 30 de abril. Na oportunidade, os representantes da autarquia apresentaram uma pauta com quatro itens de reivindica\u00e7\u00f5es da categoria.<\/p>\n<p>Da lista apresentada fazem parte: a cria\u00e7\u00e3o da carreira de Estado para m\u00e9dicos na rede p\u00fablica (SUS); e a defini\u00e7\u00e3o do Exame Nacional de Revalida\u00e7\u00e3o de Diplomas M\u00e9dicos (Revalida), por meio de lei federal, como \u00fanica forma de acesso dos portadores de diplomas de Medicina obtidos no exterior ao mercado brasileiro.<\/p>\n<p>Os m\u00e9dicos pediram ainda o reconhecimento do Sistema de Acredita\u00e7\u00e3o de Escolas M\u00e9dicas (Saeme), do CFM, como plataforma oficial de avalia\u00e7\u00e3o de cursos de medicina no Pa\u00eds; e a atualiza\u00e7\u00e3o do Decreto Presidencial n\u00ba 44.054\/1958, que regulamenta a Lei n\u00ba 3.268\/1957, em fun\u00e7\u00e3o de legisla\u00e7\u00f5es e pr\u00e1ticas vigentes.<\/p>\n<p>\u201cFoi uma reuni\u00e3o produtiva e com sinaliza\u00e7\u00e3o positiva por parte do presidente para os pleitos apresentados pelos m\u00e9dicos, por meio do CFM. Entendemos que foi dado um importante passo para a implementa\u00e7\u00e3o desses projetos que ser\u00e3o fundamentais para manter a qualidade da assist\u00eancia e do ensino da medicina no Brasil\u201d, pontuou o presidente do CFM, Carlos Vital, ap\u00f3s a reuni\u00e3o.<\/p>\n<p><strong>Carreira &#8211;<\/strong> Dos quatro pleitos, o mais antigo \u00e9 o que prev\u00ea a cria\u00e7\u00e3o de uma carreira de estado para o m\u00e9dico que atua no SUS. Atualmente, este tema tem sido discutido no \u00e2mbito do Minist\u00e9rio da Sa\u00fade, sendo que tamb\u00e9m h\u00e1 a Proposta de Emenda Constitucional n\u00ba 454\/2009, de autoria do ent\u00e3o senador Ronaldo Caiado, que se encontra pronta para ser colocada em vota\u00e7\u00e3o no Plen\u00e1rio da C\u00e2mara dos Deputados.<\/p>\n<p>O pedido dos m\u00e9dicos \u00e9 que essa carreira seja implementada com acesso por meio de concurso p\u00fablico, sendo que dentre suas caracter\u00edsticas constam o compromisso do gestor de garantir aos munic\u00edpios onde as vagas ser\u00e3o disponibilizadas a infraestrutura adequada para a oferta de assist\u00eancia segundo padr\u00f5es de qualidade; bem como a uma rede eficaz de refer\u00eancia para encaminhamento de casos mais graves.<\/p>\n<p>Os interessados contariam com uma remunera\u00e7\u00e3o adequada para permitir a dedica\u00e7\u00e3o exclusiva, a oferta de um programa de educa\u00e7\u00e3o continuada (presencial e \u00e0 dist\u00e2ncia) e a possibilidade de progress\u00e3o funcional, nos moldes dos empregados atualmente pelo Minist\u00e9rio P\u00fablico e pelo Poder Judici\u00e1rio. \u201cEsse \u00e9 um projeto que pode ajudar a resolver, de forma estruturada, os problemas de fixa\u00e7\u00e3o de m\u00e9dicos em \u00e1reas distantes\u201d, ressaltou Jos\u00e9 Hiran Gallo, diretor-Tesoureiro do CFM.<\/p>\n<p><strong>Exame \u2013<\/strong> Sobre o Exame Nacional de Revalida\u00e7\u00e3o de Diplomas M\u00e9dicos (Revalida), o CFM prop\u00f4s que ele seja estabelecido por meio de lei, tornando-se a \u00fanica forma de acesso dos portadores de diplomas de Medicina obtidos no exterior ao mercado brasileiro. \u201cEssa medida reduz a possibilidade de exposi\u00e7\u00e3o a profissionais sem a devida qualifica\u00e7\u00e3o ao aplicar um instrumento de avalia\u00e7\u00e3o justo, id\u00f4neo e transparente, capaz de mensurar os candidatos em fun\u00e7\u00e3o de seu conhecimento, habilidades e atitudes\u201d, destacou o conselheiro Hermann von Tiesenhausen, diretor de Comunica\u00e7\u00e3o do CFM.<\/p>\n<p>No escopo dessa legaliza\u00e7\u00e3o do processo, o CFM pleiteou junto \u00e0 Presid\u00eancia da Rep\u00fablica que a coordena\u00e7\u00e3o do Exame passe para sua responsabilidade, como j\u00e1 foi sugerido, inclusive, pelo Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep), ligado ao Minist\u00e9rio da Educa\u00e7\u00e3o, que tem conduzido as provas desde sua cria\u00e7\u00e3o. O pedido do CFM est\u00e1 no escopo do Projeto de Lei n\u00ba 4.067\/2015, da C\u00e2mara dos Deputados, que se encontra pronto para vota\u00e7\u00e3o na sua Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da C\u00e2mara em car\u00e1ter terminativo. Se aprovado, ele segue direto para san\u00e7\u00e3o presidencial.<\/p>\n<p><strong>Acredita\u00e7\u00e3o \u2013<\/strong> Outra proposta dos m\u00e9dicos ao Presidente \u00e9 de que seja feito o reconhecimento do Sistema de Acredita\u00e7\u00e3o de Escolas M\u00e9dicas (Saeme), do CFM, como plataforma oficial de valida\u00e7\u00e3o da qualidade de cursos de medicina no Pa\u00eds. O projeto, em vigor desde 2015, j\u00e1 certificou 32 programas de gradua\u00e7\u00e3o no Brasil, a partir de crit\u00e9rios espec\u00edficos.<\/p>\n<p>Inspirado na experi\u00eancia de sucesso do Liaison Committee on Medical Education (LCME) \u2013 processo oficial de acredita\u00e7\u00e3o dos cursos de medicina dos Estados Unidos e Canad\u00e1 \u2013, o Saeme j\u00e1 cumpriu uma s\u00e9rie de requisitos e est\u00e1 a um passo de ser reconhecido pela World Federation For Medical Education (WFME), a maior entidade mundial no tema.<\/p>\n<p>\u201cRessalte-se que a partir de 2023, m\u00e9dicos brasileiros interessados em imigrar (candidatando-se ao exerc\u00edcio da profiss\u00e3o) ou participar de programas de p\u00f3s-gradua\u00e7\u00e3o em medicina nos Estados Unidos somente poder\u00e3o faz\u00ea-lo se forem egressos de escolas certificadas por sistema de acredita\u00e7\u00e3o reconhecidos pela WFME\u201d, ressaltou o 1\u00ba vice-presidente do CFM, Mauro Ribeiro.<\/p>\n<p>Segundo ele, com a oficializa\u00e7\u00e3o do Saeme pelo Governo Federal, o Minist\u00e9rio da Educa\u00e7\u00e3o, por meio de conv\u00eanio com o CFM, poderia utilizar esse instrumento para fazer o reconhecimento e\/ou a certifica\u00e7\u00e3o de cursos de medicina.<\/p>\n<p><strong>Moderniza\u00e7\u00e3o \u2013<\/strong> A atualiza\u00e7\u00e3o do Decreto Presidencial n\u00ba 44.054\/1958, que regulamenta a Lei n\u00ba 3.268\/1957, foi o \u00faltimo ponto da pauta entregue no encontro com o presidente Jair Bolsonaro. A diretoria informou que o CFM se disp\u00f5e a ajudar na elabora\u00e7\u00e3o de novo texto. \u201cQueremos promover a moderniza\u00e7\u00e3o dessa norma, que j\u00e1 completa seis d\u00e9cadas sem nunca ter passado por uma revis\u00e3o. Ao estabelecer esse processo, pretende-se a adequ\u00e1-la \u00e0s legisla\u00e7\u00f5es e pr\u00e1ticas vigentes, o que trar\u00e1 avan\u00e7os para o exerc\u00edcio da medicina no Pa\u00eds\u201d, destacou o 3\u00ba vice-presidente Emmanuel Fortes.<\/p>\n<p>Segundo Fortes, na conversa com o presidente Bolsonaro foi ressaltado o compromisso dos m\u00e9dicos com o Brasil e o empenho da categoria com a defesa do interesse p\u00fablico, com a oferta de servi\u00e7os de sa\u00fade de qualidade e com o aprimoramento do SUS. \u201cNesse sentido, para garantir a efetividade da assist\u00eancia, atualmente, os m\u00e9dicos em atividade no Pa\u00eds, mesmo sob condi\u00e7\u00f5es adversas, t\u00eam empenhado esfor\u00e7os para atender a popula\u00e7\u00e3o, em especial as parcelas menos favorecidas da sociedade\u201d, destacou.,<\/p>\n<p><strong>Produ\u00e7\u00e3o &#8211;<\/strong> O 2\u00ba vice-presidente do CFM, Jec\u00e9 Brand\u00e3o, destacou os n\u00fameros que confirmam o que chamou de engajamento c\u00edvico dos m\u00e9dicos com a sa\u00fade brasileira. Segundo dados do Minist\u00e9rio da Sa\u00fade, entre 2014 e 2018, apenas nos servi\u00e7os da rede p\u00fablica, esses profissionais estiveram diretamente envolvidos em 1,3 bilh\u00e3o de consultas (de todos os n\u00edveis de complexidade); em 22,7 milh\u00f5es de procedimentos cir\u00fargicos; e em 342 mil transplantes de \u00f3rg\u00e3os e tecidos. Desse total, 655 milh\u00f5es de atendimentos foram realizados em prontos-socorros e Unidades de Pronto Atendimento (Upas).<\/p>\n<p>Infelizmente, a equa\u00e7\u00e3o entre demanda expressiva e dificuldades para o exerc\u00edcio da profiss\u00e3o tem cobrado seu pre\u00e7o. De acordo com Brand\u00e3o, \u201cface \u00e0 infraestrutura deficit\u00e1ria (falta de leitos, insumos, medicamentos e equipes de apoio), o que t\u00eam contribu\u00eddo para o aumento de casos de agress\u00e3o de pacientes e familiares contra os profissionais; e \u00e0 precariza\u00e7\u00e3o de v\u00ednculos empregat\u00edcios, com consequente instabilidade funcional e remunera\u00e7\u00e3o aqu\u00e9m da sua responsabilidade e preparo exigido; os m\u00e9dicos brasileiros se sentem desvalorizados e n\u00e3o reconhecidos. Inclusive, h\u00e1 estudos que sugerem que essa situa\u00e7\u00e3o tem levado ao aumento da incid\u00eancia de doen\u00e7as decorrentes do stress e da S\u00edndrome de Burnout na categoria\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o do CFM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa reuni\u00e3o de quase duas horas, no Pal\u00e1cio do Planalto, a diretoria do Conselho Federal de Medicina (CFM) apresentou hoje (16) ao presidente da Rep\u00fablica, Jair Bolsonaro, e ao ministro da Sa\u00fade, Henrique Mandetta, o novo C\u00f3digo de \u00c9tica M\u00e9dica (CEM), detalhado na Resolu\u00e7\u00e3o n\u00ba 2.217\/2018 e que entra vigor no pr\u00f3ximo dia 30 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[67,229,82],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52418"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52418"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52418\/revisions"}],"predecessor-version":[{"id":52419,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52418\/revisions\/52419"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}