{"id":52632,"date":"2019-04-29T09:07:16","date_gmt":"2019-04-29T12:07:16","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52632"},"modified":"2019-04-29T09:07:16","modified_gmt":"2019-04-29T12:07:16","slug":"pagamento-da-diferenca-da-gratificacao-dos-medicos-federais-sera-solicitada-ao-governo-pela-frente-parlamentar-da-medicina","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/pagamento-da-diferenca-da-gratificacao-dos-medicos-federais-sera-solicitada-ao-governo-pela-frente-parlamentar-da-medicina\/","title":{"rendered":"Pagamento da diferen\u00e7a da gratifica\u00e7\u00e3o dos m\u00e9dicos federais ser\u00e1 solicitada ao governo pela Frente Parlamentar da Medicina"},"content":{"rendered":"<p style=\"text-align: justify;\">O presidente da FENAM, Jorge Darze, foi recebido, nesta quinta-feira (25), em Bras\u00edlia, pelo deputado Hiran Gon\u00e7alves (PP\/RO), presidente da Frente Parlamentar da Medicina do Congresso Nacional, para falar sobre a gratifica\u00e7\u00e3o por desempenho dos m\u00e9dicos federais. A inten\u00e7\u00e3o do l\u00edder m\u00e9dico foi mobilizar a Frente Parlamentar e assim unificar os esfor\u00e7os no sentido de que, na negocia\u00e7\u00e3o com o governo federal, se encontre o quanto antes uma solu\u00e7\u00e3o para efetivar o pagamento da diferen\u00e7a do valor dessa gratifica\u00e7\u00e3o. \u201cN\u00e3o vamos desistir at\u00e9 que seja corrigida essa grande injusti\u00e7a cometida pelo governo, h\u00e1 mais de cinco anos, e que, desde ent\u00e3o, vem obrigando os m\u00e9dicos federais a receberem gratifica\u00e7\u00e3o menor que das demais categorias de n\u00edvel superior do Minist\u00e9rio da Sa\u00fade\u201d, destacou Darze.<\/p>\n<p style=\"text-align: justify;\">\nA FENAM iniciou sozinha essa luta que, ap\u00f3s ter sido levada pelo seu presidente para discuss\u00e3o no Encontro Nacional das Entidades M\u00e9dicas (ENEM), recebeu uma mo\u00e7\u00e3o de apoio daquele f\u00f3rum, e passou a ser tamb\u00e9m uma das bandeiras de luta da Frente Parlamentar da Medicina.<\/p>\n<p style=\"text-align: justify;\">\nO deputado Hiran Gon\u00e7alves assumiu como sua responsabilidade e da Frente Parlamentar a elabora\u00e7\u00e3o de um decreto legislativo, na C\u00e2mara dos Deputados, que recomende ao ministro da Sa\u00fade a ado\u00e7\u00e3o das medidas administrativas necess\u00e1rias para que o governo federal corrija essa distor\u00e7\u00e3o. O parlamentar afian\u00e7ou que a proposi\u00e7\u00e3o ser\u00e1 apresentada j\u00e1 na pr\u00f3xima semana.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o da FENAM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da FENAM, Jorge Darze, foi recebido, nesta quinta-feira (25), em Bras\u00edlia, pelo deputado Hiran Gon\u00e7alves (PP\/RO), presidente da Frente Parlamentar da Medicina do Congresso Nacional, para falar sobre a gratifica\u00e7\u00e3o por desempenho dos m\u00e9dicos federais. A inten\u00e7\u00e3o do l\u00edder m\u00e9dico foi mobilizar a Frente Parlamentar e assim unificar os esfor\u00e7os no sentido de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[3550,673,3500],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52632"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52632"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52632\/revisions"}],"predecessor-version":[{"id":52633,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52632\/revisions\/52633"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}