{"id":52654,"date":"2019-04-29T12:35:43","date_gmt":"2019-04-29T15:35:43","guid":{"rendered":"http:\/\/www.simepe.com.br\/novo\/?p=52654"},"modified":"2019-04-29T12:35:43","modified_gmt":"2019-04-29T15:35:43","slug":"congresso-de-pediatria-em-petrolina-e-juazeiro","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/congresso-de-pediatria-em-petrolina-e-juazeiro\/","title":{"rendered":"Congresso de pediatria em Petrolina e Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020.jpg\" rel=\"attachment wp-att-52655\"><img fetchpriority=\"high\" class=\"aligncenter size-full wp-image-52655\" src=\"http:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020.jpg\" alt=\"05d8e49a-e592-4f60-b41b-5685eecb5020\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020.jpg 1000w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-150x150.jpg 150w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-300x300.jpg 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-768x768.jpg 768w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-80x80.jpg 80w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-360x360.jpg 360w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2019\/04\/05d8e49a-e592-4f60-b41b-5685eecb5020-750x750.jpg 750w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">O 1\u00ba Congresso Integrado de Pediatria do Nordeste (Nordesteped), de 1 a 3 maio, ser\u00e1 o primeiro evento cient\u00edfico da Sociedade Brasileira de Pediatria realizado no interior de um estado. Neste caso, em duas cidades: Petrolina e Juazeiro. As sociedades de pediatria dos nove estados da regi\u00e3o est\u00e3o envolvidas na organiza\u00e7\u00e3o do encontro, que serve para atualiza\u00e7\u00e3o e interc\u00e2mbio de conhecimentos, tendo uma ampla programa\u00e7\u00e3o. Na v\u00e9spera da abertura oficial haver\u00e1 um curso pr\u00e9-congresso sobre reanima\u00e7\u00e3o neonatal.<\/p>\n<p style=\"text-align: justify;\">A presidente da SBP, Luciana Rodrigues Silva, estar\u00e1 presente, no primeiro evento ap\u00f3s a reelei\u00e7\u00e3o da sua diretoria, que aconteceu nesta semana. Para ela, o evento serve para unir ainda mais as filiadas. \u201cEste Congresso vem para consagrar o compromisso de integrar os pediatras de todo o Pa\u00eds, sobretudo os do Nordeste\u201d. Os especialistas ter\u00e3o acesso a uma grade cient\u00edfica atualizada e adequada \u00e0 realidade cotidiana do pediatra.<\/p>\n<p style=\"text-align: justify;\">O Congresso contar\u00e1 com mini-confer\u00eancias, mesas-redondas e confer\u00eancias. Segundo o presidente do Congresso e da Sociedade de Pediatria de Pernambuco (Sopepe), Eduardo Jorge da Fonseca Lima, o pediatra \u00e9 o p\u00fablico-alvo principal do evento, mas todos os profissionais de sa\u00fade que trabalham diretamente com crian\u00e7as poder\u00e3o participar, assim como estudantes e residentes. \u201cAl\u00e9m da grade cient\u00edfica, ser\u00e1 poss\u00edvel trocar experi\u00eancias com os professores participantes e com outros congressistas de v\u00e1rias regi\u00f5es do pa\u00eds e, especialmente, do Nordeste\u201d, afirma Eduardo Jorge.<\/p>\n<p style=\"text-align: justify;\">Os temas da programa\u00e7\u00e3o do congresso abordam nutri\u00e7\u00e3o e imunidade; intoler\u00e2ncia \u00e0 lactose; alergia \u00e0 prote\u00edna do leite de vaca; cuidados paliativos em neonatologia e pediatria; hip\u00f3xia perinatal; diagn\u00f3stico de desordens comportamentais; calend\u00e1rio vacinal; preven\u00e7\u00e3o da doen\u00e7a neningoc\u00f3cica; cuidados paliativos em neonatologia e pediatria; transtornos do espectro autista; coqueluche; reposi\u00e7\u00e3o de vacinas; jogos educativos e digitais na inf\u00e2ncia e adolesc\u00eancia; neurodesenvolvimento; o movimento antivacina e suas consequ\u00eancias, entre outros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fonte: Assessoria de Comunica\u00e7\u00e3o da Sociedade Brasileira de Pediatria (SBP)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O 1\u00ba Congresso Integrado de Pediatria do Nordeste (Nordesteped), de 1 a 3 maio, ser\u00e1 o primeiro evento cient\u00edfico da Sociedade Brasileira de Pediatria realizado no interior de um estado. Neste caso, em duas cidades: Petrolina e Juazeiro. As sociedades de pediatria dos nove estados da regi\u00e3o est\u00e3o envolvidas na organiza\u00e7\u00e3o do encontro, que serve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[9],"tags":[833,75,196],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52654"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=52654"}],"version-history":[{"count":1,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52654\/revisions"}],"predecessor-version":[{"id":52657,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/52654\/revisions\/52657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media\/52656"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=52654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=52654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=52654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}