{"id":67995,"date":"2024-11-09T09:55:09","date_gmt":"2024-11-09T12:55:09","guid":{"rendered":"https:\/\/www.simepe.com.br\/novo\/?p=67995"},"modified":"2024-11-09T09:56:16","modified_gmt":"2024-11-09T12:56:16","slug":"simepe-constata-varios-problemas-no-hospital-otavio-de-freitas-e-cobra-providencias","status":"publish","type":"post","link":"https:\/\/www.simepe.com.br\/novo\/simepe-constata-varios-problemas-no-hospital-otavio-de-freitas-e-cobra-providencias\/","title":{"rendered":"Simepe constata v\u00e1rios problemas no Hospital Ot\u00e1vio de Freitas e cobra provid\u00eancias \u00e0 dire\u00e7\u00e3o"},"content":{"rendered":"<p>Com objetivo de apurar den\u00fancias dos m\u00e9dicos plantonistas da emerg\u00eancia do Hospital Ot\u00e1vio de Freitas, os diretores do Sindicato dos Medicos de Pernambuco (Simepe),\u00a0 Rodrigo Rosas e Fernando Junior\u00a0 visitaram, nesta sexta-feira (08\/11), o estar m\u00e9dico e constataram uma s\u00e9rie de problemas e precariedades na infraestrutura hospitalar.<\/p>\n<p><img fetchpriority=\"high\" class=\"alignnone size-full wp-image-67997\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/12.png\" alt=\"\" width=\"777\" height=\"516\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/12.png 777w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/12-300x199.png 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/12-768x510.png 768w\" sizes=\"(max-width: 777px) 100vw, 777px\" \/><\/p>\n<p>Por exemplo: ar condicionado vazando, com po\u00e7as de \u00e1gua no ch\u00e3o, paredes infiltradas e mofadas, estrados das camas quebrados, banheiros sem portas, sem trancas, fios expostos, o piso do quarto em p\u00e9ssimas condi\u00e7\u00f5es. Enfim, uma situa\u00e7\u00e3o muito ruim para os profissionais.<\/p>\n<p><img class=\"alignnone size-full wp-image-67999\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13.png\" alt=\"\" width=\"1120\" height=\"518\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13.png 1120w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13-300x139.png 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13-1024x474.png 1024w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13-768x355.png 768w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/13-165x75.png 165w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p><img class=\"alignnone size-full wp-image-68003\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/16.png\" alt=\"\" width=\"790\" height=\"508\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/16.png 790w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/16-300x193.png 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/16-768x494.png 768w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><\/p>\n<p>O diretor Rodrigo Rosas explicou: \u201cN\u00f3s viemos aqui, conversamos com a dire\u00e7\u00e3o e estamos cobrando as provid\u00eancias, que tudo seja regularizado. Tem problemas que v\u00e3o ser resolvidos imediatamente, que s\u00e3o problemas simples, outros s\u00e3o estruturais que v\u00e3o demorar mais, como por exemplo a infiltra\u00e7\u00e3o\u201d, ressaltou.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-68004\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/25.jpg\" alt=\"\" width=\"847\" height=\"512\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/25.jpg 847w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/25-300x181.jpg 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/25-768x464.jpg 768w\" sizes=\"(max-width: 847px) 100vw, 847px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-68002\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/15-1.jpg\" alt=\"\" width=\"332\" height=\"641\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/15-1.jpg 332w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/15-1-155x300.jpg 155w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/><\/p>\n<p>Ele enfatizou que o ar condicionado no repouso volante, s\u00f3 tem um, n\u00e3o est\u00e1 gelando, mas pode-se trazer um segundo ar condicionado. S\u00e3o coisas simples, que d\u00e3o conforto e uma melhor qualidade ao plant\u00e3o aos m\u00e9dicos que est\u00e3o de plant\u00e3o.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-68005\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21.png\" alt=\"\" width=\"1120\" height=\"518\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21.png 1120w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21-300x139.png 300w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21-1024x474.png 1024w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21-768x355.png 768w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/21-165x75.png 165w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-68006\" src=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/rodrigo.jpg\" alt=\"\" width=\"363\" height=\"784\" srcset=\"https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/rodrigo.jpg 363w, https:\/\/www.simepe.com.br\/novo\/wp-content\/uploads\/2024\/11\/rodrigo-139x300.jpg 139w\" sizes=\"(max-width: 363px) 100vw, 363px\" \/><\/p>\n<p>Durante a reuni\u00e3o, os diretores do Simepe cobraram um cronograma \u00e0 dire\u00e7\u00e3o do Ot\u00e1vio de Freitas que prometeu entregar na pr\u00f3xima segunda-feira, dia 11\/11. Daqui a tr\u00eas semanas, o Sindicato voltar\u00e1 para ver se houve melhorias ou n\u00e3o.<\/p>\n<p>O Simepe segue atento \u00e0s demandas dos m\u00e9dicos plantonistas, buscando solu\u00e7\u00f5es que tragam melhorias tanto para os profissionais quanto para o atendimento oferecido aos pacientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com objetivo de apurar den\u00fancias dos m\u00e9dicos plantonistas da emerg\u00eancia do Hospital Ot\u00e1vio de Freitas, os diretores do Sindicato dos Medicos de Pernambuco (Simepe),\u00a0 Rodrigo Rosas e Fernando Junior\u00a0 visitaram, nesta sexta-feira (08\/11), o estar m\u00e9dico e constataram uma s\u00e9rie de problemas e precariedades na infraestrutura hospitalar. Por exemplo: ar condicionado vazando, com po\u00e7as de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[]},"categories":[1796,1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/67995"}],"collection":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/comments?post=67995"}],"version-history":[{"count":2,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/67995\/revisions"}],"predecessor-version":[{"id":68008,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/posts\/67995\/revisions\/68008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media\/67996"}],"wp:attachment":[{"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/media?parent=67995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/categories?post=67995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simepe.com.br\/novo\/wp-json\/wp\/v2\/tags?post=67995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}